{"id":7023,"date":"2026-01-05T16:11:56","date_gmt":"2026-01-05T19:11:56","guid":{"rendered":"https:\/\/sbrv.org\/medico\/?p=7023"},"modified":"2026-03-11T16:15:33","modified_gmt":"2026-03-11T19:15:33","slug":"atencao-associados-da-sbrv-%f0%9f%93%a2","status":"publish","type":"post","link":"https:\/\/sbrv.org\/medico\/atencao-associados-da-sbrv-%f0%9f%93%a2\/","title":{"rendered":"Aten\u00e7\u00e3o, associados da SBRV! \ud83d\udce2"},"content":{"rendered":"\n<p>Prazo final prorrogado para o pagamento da anuidade, sem acr\u00e9scimos. Durante o prazo anteriormente estipulado, alguns associados referiram dificuldades e instabilidade no sistema de recebimento. Assim, para seu maior conforto e garantia do valor, o prazo foi estendido para 31\/01. Garanta sua regularidade e continue aproveitando os benef\u00edcios exclusivos oferecidos pela SBRV.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-id=\"7024\" src=\"https:\/\/sbrv.org\/medico\/wp-content\/uploads\/sites\/2\/2026\/03\/609096740_18357838201206067_7109267056168593213_n-819x1024.jpg\" alt=\"\" class=\"wp-image-7024\" srcset=\"https:\/\/sbrv.org\/medico\/wp-content\/uploads\/sites\/2\/2026\/03\/609096740_18357838201206067_7109267056168593213_n-819x1024.jpg 819w, https:\/\/sbrv.org\/medico\/wp-content\/uploads\/sites\/2\/2026\/03\/609096740_18357838201206067_7109267056168593213_n-240x300.jpg 240w, https:\/\/sbrv.org\/medico\/wp-content\/uploads\/sites\/2\/2026\/03\/609096740_18357838201206067_7109267056168593213_n-768x960.jpg 768w, https:\/\/sbrv.org\/medico\/wp-content\/uploads\/sites\/2\/2026\/03\/609096740_18357838201206067_7109267056168593213_n.jpg 1080w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-id=\"7026\" src=\"https:\/\/sbrv.org\/medico\/wp-content\/uploads\/sites\/2\/2026\/03\/610664304_18357838216206067_311412075884759088_n-819x1024.jpg\" alt=\"\" class=\"wp-image-7026\" srcset=\"https:\/\/sbrv.org\/medico\/wp-content\/uploads\/sites\/2\/2026\/03\/610664304_18357838216206067_311412075884759088_n-819x1024.jpg 819w, https:\/\/sbrv.org\/medico\/wp-content\/uploads\/sites\/2\/2026\/03\/610664304_18357838216206067_311412075884759088_n-240x300.jpg 240w, https:\/\/sbrv.org\/medico\/wp-content\/uploads\/sites\/2\/2026\/03\/610664304_18357838216206067_311412075884759088_n-768x960.jpg 768w, https:\/\/sbrv.org\/medico\/wp-content\/uploads\/sites\/2\/2026\/03\/610664304_18357838216206067_311412075884759088_n.jpg 1080w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" data-id=\"7025\" src=\"https:\/\/sbrv.org\/medico\/wp-content\/uploads\/sites\/2\/2026\/03\/609204622_18357838228206067_7115663930671823495_n-819x1024.jpg\" alt=\"\" class=\"wp-image-7025\" srcset=\"https:\/\/sbrv.org\/medico\/wp-content\/uploads\/sites\/2\/2026\/03\/609204622_18357838228206067_7115663930671823495_n-819x1024.jpg 819w, https:\/\/sbrv.org\/medico\/wp-content\/uploads\/sites\/2\/2026\/03\/609204622_18357838228206067_7115663930671823495_n-240x300.jpg 240w, https:\/\/sbrv.org\/medico\/wp-content\/uploads\/sites\/2\/2026\/03\/609204622_18357838228206067_7115663930671823495_n-768x960.jpg 768w, https:\/\/sbrv.org\/medico\/wp-content\/uploads\/sites\/2\/2026\/03\/609204622_18357838228206067_7115663930671823495_n.jpg 1080w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>Meios de pagamento dispon\u00edveis: boleto, cart\u00e3o parcelado ou PIX.<\/p>\n\n\n\n<p>Acesse: anuidade.sbrv.org (ou link na bio)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prazo final prorrogado para o pagamento da anuidade, sem acr\u00e9scimos. Durante o prazo anteriormente estipulado, alguns associados referiram dificuldades e instabilidade no sistema de recebimento. Assim, para seu maior conforto e garantia do valor, o prazo foi estendido para 31\/01. Garanta sua regularidade e continue aproveitando os benef\u00edcios exclusivos oferecidos pela SBRV. Meios de pagamento [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7024,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-7023","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aten\u00e7\u00e3o, associados da SBRV! \ud83d\udce2 - SBRV - \u00c1rea do M\u00e9dico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sbrv.org\/medico\/atencao-associados-da-sbrv-\ud83d\udce2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aten\u00e7\u00e3o, associados da SBRV! \ud83d\udce2 - SBRV - \u00c1rea do M\u00e9dico\" \/>\n<meta property=\"og:description\" content=\"Prazo final prorrogado para o pagamento da anuidade, sem acr\u00e9scimos. Durante o prazo anteriormente estipulado, alguns associados referiram dificuldades e instabilidade no sistema de recebimento. Assim, para seu maior conforto e garantia do valor, o prazo foi estendido para 31\/01. Garanta sua regularidade e continue aproveitando os benef\u00edcios exclusivos oferecidos pela SBRV. Meios de pagamento [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sbrv.org\/medico\/atencao-associados-da-sbrv-\ud83d\udce2\/\" \/>\n<meta property=\"og:site_name\" content=\"SBRV - \u00c1rea do M\u00e9dico\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/pt-br.facebook.com\/sbrv.retina\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-05T19:11:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-11T19:15:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sbrv.org\/medico\/wp-content\/uploads\/sites\/2\/2026\/03\/609096740_18357838201206067_7109267056168593213_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Planeta W\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@sbrv_retina\" \/>\n<meta name=\"twitter:site\" content=\"@sbrv_retina\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Planeta W\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/atencao-associados-da-sbrv-%f0%9f%93%a2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/atencao-associados-da-sbrv-%f0%9f%93%a2\\\/\"},\"author\":{\"name\":\"Planeta W\",\"@id\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/#\\\/schema\\\/person\\\/73c83589d85c9b45c2a25e66bf09e4ea\"},\"headline\":\"Aten\u00e7\u00e3o, associados da SBRV! \ud83d\udce2\",\"datePublished\":\"2026-01-05T19:11:56+00:00\",\"dateModified\":\"2026-03-11T19:15:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/atencao-associados-da-sbrv-%f0%9f%93%a2\\\/\"},\"wordCount\":77,\"publisher\":{\"@id\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/atencao-associados-da-sbrv-%f0%9f%93%a2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/609096740_18357838201206067_7109267056168593213_n.jpg\",\"articleSection\":[\"Not\u00edcias\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/atencao-associados-da-sbrv-%f0%9f%93%a2\\\/\",\"url\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/atencao-associados-da-sbrv-%f0%9f%93%a2\\\/\",\"name\":\"Aten\u00e7\u00e3o, associados da SBRV! \ud83d\udce2 - SBRV - \u00c1rea do M\u00e9dico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/atencao-associados-da-sbrv-%f0%9f%93%a2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/atencao-associados-da-sbrv-%f0%9f%93%a2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/609096740_18357838201206067_7109267056168593213_n.jpg\",\"datePublished\":\"2026-01-05T19:11:56+00:00\",\"dateModified\":\"2026-03-11T19:15:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/atencao-associados-da-sbrv-%f0%9f%93%a2\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sbrv.org\\\/medico\\\/atencao-associados-da-sbrv-%f0%9f%93%a2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/atencao-associados-da-sbrv-%f0%9f%93%a2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/609096740_18357838201206067_7109267056168593213_n.jpg\",\"contentUrl\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2026\\\/03\\\/609096740_18357838201206067_7109267056168593213_n.jpg\",\"width\":1080,\"height\":1350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/atencao-associados-da-sbrv-%f0%9f%93%a2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aten\u00e7\u00e3o, associados da SBRV! \ud83d\udce2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/#website\",\"url\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/\",\"name\":\"SBRV - Sociedade Brasileira de Retina e Vitreo - \u00c1rea do M\u00e9dico\",\"description\":\"Portal da Sociedade Brasileira de Retina e Vitreo\",\"publisher\":{\"@id\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/#organization\"},\"alternateName\":\"SBRV\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/#organization\",\"name\":\"SBRV - Sociedade Brasileira de Retina e Vitreo\",\"alternateName\":\"SBRV\",\"url\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/12\\\/thumbnail-default-2.png\",\"contentUrl\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2024\\\/12\\\/thumbnail-default-2.png\",\"width\":600,\"height\":400,\"caption\":\"SBRV - Sociedade Brasileira de Retina e Vitreo\"},\"image\":{\"@id\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/pt-br.facebook.com\\\/sbrv.retina\",\"https:\\\/\\\/x.com\\\/sbrv_retina\",\"https:\\\/\\\/www.instagram.com\\\/retina.sbrv\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/#\\\/schema\\\/person\\\/73c83589d85c9b45c2a25e66bf09e4ea\",\"name\":\"Planeta W\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9ef65b90e46440593e836e33222c601a63b314140d0be8f0d47de6fe79ef055?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9ef65b90e46440593e836e33222c601a63b314140d0be8f0d47de6fe79ef055?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f9ef65b90e46440593e836e33222c601a63b314140d0be8f0d47de6fe79ef055?s=96&d=mm&r=g\",\"caption\":\"Planeta W\"},\"sameAs\":[\"https:\\\/\\\/sbrv.org\"],\"url\":\"https:\\\/\\\/sbrv.org\\\/medico\\\/author\\\/q5cyu8e9nd\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aten\u00e7\u00e3o, associados da SBRV! \ud83d\udce2 - SBRV - \u00c1rea do M\u00e9dico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sbrv.org\/medico\/atencao-associados-da-sbrv-\ud83d\udce2\/","og_locale":"pt_BR","og_type":"article","og_title":"Aten\u00e7\u00e3o, associados da SBRV! \ud83d\udce2 - SBRV - \u00c1rea do M\u00e9dico","og_description":"Prazo final prorrogado para o pagamento da anuidade, sem acr\u00e9scimos. Durante o prazo anteriormente estipulado, alguns associados referiram dificuldades e instabilidade no sistema de recebimento. Assim, para seu maior conforto e garantia do valor, o prazo foi estendido para 31\/01. Garanta sua regularidade e continue aproveitando os benef\u00edcios exclusivos oferecidos pela SBRV. Meios de pagamento [&hellip;]","og_url":"https:\/\/sbrv.org\/medico\/atencao-associados-da-sbrv-\ud83d\udce2\/","og_site_name":"SBRV - \u00c1rea do M\u00e9dico","article_publisher":"https:\/\/pt-br.facebook.com\/sbrv.retina","article_published_time":"2026-01-05T19:11:56+00:00","article_modified_time":"2026-03-11T19:15:33+00:00","og_image":[{"width":1080,"height":1350,"url":"https:\/\/sbrv.org\/medico\/wp-content\/uploads\/sites\/2\/2026\/03\/609096740_18357838201206067_7109267056168593213_n.jpg","type":"image\/jpeg"}],"author":"Planeta W","twitter_card":"summary_large_image","twitter_creator":"@sbrv_retina","twitter_site":"@sbrv_retina","twitter_misc":{"Escrito por":"Planeta W","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sbrv.org\/medico\/atencao-associados-da-sbrv-%f0%9f%93%a2\/#article","isPartOf":{"@id":"https:\/\/sbrv.org\/medico\/atencao-associados-da-sbrv-%f0%9f%93%a2\/"},"author":{"name":"Planeta W","@id":"https:\/\/sbrv.org\/medico\/#\/schema\/person\/73c83589d85c9b45c2a25e66bf09e4ea"},"headline":"Aten\u00e7\u00e3o, associados da SBRV! \ud83d\udce2","datePublished":"2026-01-05T19:11:56+00:00","dateModified":"2026-03-11T19:15:33+00:00","mainEntityOfPage":{"@id":"https:\/\/sbrv.org\/medico\/atencao-associados-da-sbrv-%f0%9f%93%a2\/"},"wordCount":77,"publisher":{"@id":"https:\/\/sbrv.org\/medico\/#organization"},"image":{"@id":"https:\/\/sbrv.org\/medico\/atencao-associados-da-sbrv-%f0%9f%93%a2\/#primaryimage"},"thumbnailUrl":"https:\/\/sbrv.org\/medico\/wp-content\/uploads\/sites\/2\/2026\/03\/609096740_18357838201206067_7109267056168593213_n.jpg","articleSection":["Not\u00edcias"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/sbrv.org\/medico\/atencao-associados-da-sbrv-%f0%9f%93%a2\/","url":"https:\/\/sbrv.org\/medico\/atencao-associados-da-sbrv-%f0%9f%93%a2\/","name":"Aten\u00e7\u00e3o, associados da SBRV! \ud83d\udce2 - SBRV - \u00c1rea do M\u00e9dico","isPartOf":{"@id":"https:\/\/sbrv.org\/medico\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sbrv.org\/medico\/atencao-associados-da-sbrv-%f0%9f%93%a2\/#primaryimage"},"image":{"@id":"https:\/\/sbrv.org\/medico\/atencao-associados-da-sbrv-%f0%9f%93%a2\/#primaryimage"},"thumbnailUrl":"https:\/\/sbrv.org\/medico\/wp-content\/uploads\/sites\/2\/2026\/03\/609096740_18357838201206067_7109267056168593213_n.jpg","datePublished":"2026-01-05T19:11:56+00:00","dateModified":"2026-03-11T19:15:33+00:00","breadcrumb":{"@id":"https:\/\/sbrv.org\/medico\/atencao-associados-da-sbrv-%f0%9f%93%a2\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sbrv.org\/medico\/atencao-associados-da-sbrv-%f0%9f%93%a2\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sbrv.org\/medico\/atencao-associados-da-sbrv-%f0%9f%93%a2\/#primaryimage","url":"https:\/\/sbrv.org\/medico\/wp-content\/uploads\/sites\/2\/2026\/03\/609096740_18357838201206067_7109267056168593213_n.jpg","contentUrl":"https:\/\/sbrv.org\/medico\/wp-content\/uploads\/sites\/2\/2026\/03\/609096740_18357838201206067_7109267056168593213_n.jpg","width":1080,"height":1350},{"@type":"BreadcrumbList","@id":"https:\/\/sbrv.org\/medico\/atencao-associados-da-sbrv-%f0%9f%93%a2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sbrv.org\/medico\/"},{"@type":"ListItem","position":2,"name":"Aten\u00e7\u00e3o, associados da SBRV! \ud83d\udce2"}]},{"@type":"WebSite","@id":"https:\/\/sbrv.org\/medico\/#website","url":"https:\/\/sbrv.org\/medico\/","name":"SBRV - Sociedade Brasileira de Retina e Vitreo - \u00c1rea do M\u00e9dico","description":"Portal da Sociedade Brasileira de Retina e Vitreo","publisher":{"@id":"https:\/\/sbrv.org\/medico\/#organization"},"alternateName":"SBRV","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sbrv.org\/medico\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/sbrv.org\/medico\/#organization","name":"SBRV - Sociedade Brasileira de Retina e Vitreo","alternateName":"SBRV","url":"https:\/\/sbrv.org\/medico\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/sbrv.org\/medico\/#\/schema\/logo\/image\/","url":"https:\/\/sbrv.org\/medico\/wp-content\/uploads\/sites\/2\/2024\/12\/thumbnail-default-2.png","contentUrl":"https:\/\/sbrv.org\/medico\/wp-content\/uploads\/sites\/2\/2024\/12\/thumbnail-default-2.png","width":600,"height":400,"caption":"SBRV - Sociedade Brasileira de Retina e Vitreo"},"image":{"@id":"https:\/\/sbrv.org\/medico\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/pt-br.facebook.com\/sbrv.retina","https:\/\/x.com\/sbrv_retina","https:\/\/www.instagram.com\/retina.sbrv\/"]},{"@type":"Person","@id":"https:\/\/sbrv.org\/medico\/#\/schema\/person\/73c83589d85c9b45c2a25e66bf09e4ea","name":"Planeta W","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/f9ef65b90e46440593e836e33222c601a63b314140d0be8f0d47de6fe79ef055?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f9ef65b90e46440593e836e33222c601a63b314140d0be8f0d47de6fe79ef055?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f9ef65b90e46440593e836e33222c601a63b314140d0be8f0d47de6fe79ef055?s=96&d=mm&r=g","caption":"Planeta W"},"sameAs":["https:\/\/sbrv.org"],"url":"https:\/\/sbrv.org\/medico\/author\/q5cyu8e9nd\/"}]}},"_links":{"self":[{"href":"https:\/\/sbrv.org\/medico\/wp-json\/wp\/v2\/posts\/7023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sbrv.org\/medico\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sbrv.org\/medico\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sbrv.org\/medico\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sbrv.org\/medico\/wp-json\/wp\/v2\/comments?post=7023"}],"version-history":[{"count":1,"href":"https:\/\/sbrv.org\/medico\/wp-json\/wp\/v2\/posts\/7023\/revisions"}],"predecessor-version":[{"id":7027,"href":"https:\/\/sbrv.org\/medico\/wp-json\/wp\/v2\/posts\/7023\/revisions\/7027"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sbrv.org\/medico\/wp-json\/wp\/v2\/media\/7024"}],"wp:attachment":[{"href":"https:\/\/sbrv.org\/medico\/wp-json\/wp\/v2\/media?parent=7023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sbrv.org\/medico\/wp-json\/wp\/v2\/categories?post=7023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sbrv.org\/medico\/wp-json\/wp\/v2\/tags?post=7023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}